{"id":14144,"date":"2020-12-31T02:39:00","date_gmt":"2020-12-31T02:39:00","guid":{"rendered":"https:\/\/paolobigelli.com\/opera\/etrange-compagnons-de-jeux\/"},"modified":"2020-12-31T02:39:00","modified_gmt":"2020-12-31T02:39:00","slug":"etrange-compagnons-de-jeux","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/","title":{"rendered":"\u00c9trange compagnons de jeux"},"content":{"rendered":"<p>Acrilico su carta kraft<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acrilico su carta kraft &#8211; 2015 &#8211; 72x72cm<\/p>\n","protected":false},"featured_media":8396,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1963],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9trange compagnons de jeux - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9trange compagnons de jeux - Paolo Bigelli\" \/>\n<meta property=\"og:description\" content=\"Acrilico su carta kraft - 2015 - 72x72cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/\",\"url\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/\",\"name\":\"\u00c9trange compagnons de jeux - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg\",\"datePublished\":\"2020-12-31T02:39:00+00:00\",\"dateModified\":\"2020-12-31T02:39:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg\",\"width\":800,\"height\":815},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/www.paolobigelli.com\/pt-pt\/galeria\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9trange compagnons de jeux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/pt-pt\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9trange compagnons de jeux - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/","og_locale":"pt_PT","og_type":"article","og_title":"\u00c9trange compagnons de jeux - Paolo Bigelli","og_description":"Acrilico su carta kraft - 2015 - 72x72cm","og_url":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","og_image":[{"width":800,"height":815,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/","url":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/","name":"\u00c9trange compagnons de jeux - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg","datePublished":"2020-12-31T02:39:00+00:00","dateModified":"2020-12-31T02:39:00+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wj_Strani-compagni-di-giochi-2.jpg","width":800,"height":815},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/pt-pt\/obra\/etrange-compagnons-de-jeux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/www.paolobigelli.com\/pt-pt\/galeria\/"},{"@type":"ListItem","position":3,"name":"\u00c9trange compagnons de jeux"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/pt-pt\/#website","url":"https:\/\/www.paolobigelli.com\/pt-pt\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/pt-pt\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.paolobigelli.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/product\/14144"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=14144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/media\/8396"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=14144"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=14144"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=14144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}