{"id":16033,"date":"2023-06-13T12:06:53","date_gmt":"2023-06-13T12:06:54","guid":{"rendered":"https:\/\/www.paolobigelli.com\/?post_type=product&#038;p=16033"},"modified":"2023-06-13T12:08:12","modified_gmt":"2023-06-13T12:08:12","slug":"la-cantante-rossiniana","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/","title":{"rendered":"La cantante rossiniana"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":16037,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1961],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La cantante rossiniana - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cantante rossiniana - Paolo Bigelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-13T12:08:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1478\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/\",\"name\":\"La cantante rossiniana - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg\",\"datePublished\":\"2023-06-13T12:06:54+00:00\",\"dateModified\":\"2023-06-13T12:08:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg\",\"width\":1478,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/www.paolobigelli.com\/fr\/galerie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La cantante rossiniana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cantante rossiniana - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/","og_locale":"fr_FR","og_type":"article","og_title":"La cantante rossiniana - Paolo Bigelli","og_url":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","article_modified_time":"2023-06-13T12:08:12+00:00","og_image":[{"width":1478,"height":2048,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/","url":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/","name":"La cantante rossiniana - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg","datePublished":"2023-06-13T12:06:54+00:00","dateModified":"2023-06-13T12:08:12+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2023\/06\/11401962@N02_52305945401_La-cantante-rossiniana-The-Rossini-singer.jpg","width":1478,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/la-cantante-rossiniana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.paolobigelli.com\/fr\/galerie\/"},{"@type":"ListItem","position":3,"name":"La cantante rossiniana"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/fr\/#website","url":"https:\/\/www.paolobigelli.com\/fr\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/fr\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product\/16033"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/comments?post=16033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/media\/16037"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/media?parent=16033"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product_cat?post=16033"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product_tag?post=16033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}