{"id":14704,"date":"2021-04-07T17:23:29","date_gmt":"2021-04-07T17:23:29","guid":{"rendered":"https:\/\/paolobigelli.com\/?post_type=product&#038;p=14704"},"modified":"2021-04-07T17:24:20","modified_gmt":"2021-04-07T17:24:20","slug":"muses","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/","title":{"rendered":"Muses"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":14708,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1961],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muses - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muses - Paolo Bigelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-07T17:24:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1528\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/\",\"name\":\"Muses - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg\",\"datePublished\":\"2021-04-07T17:23:29+00:00\",\"dateModified\":\"2021-04-07T17:24:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg\",\"width\":1528,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/www.paolobigelli.com\/fr\/galerie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Muses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muses - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/","og_locale":"fr_FR","og_type":"article","og_title":"Muses - Paolo Bigelli","og_url":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","article_modified_time":"2021-04-07T17:24:20+00:00","og_image":[{"width":1528,"height":2048,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/","url":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/","name":"Muses - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg","datePublished":"2021-04-07T17:23:29+00:00","dateModified":"2021-04-07T17:24:20+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49199554672_Muse.jpg","width":1528,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/muses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.paolobigelli.com\/fr\/galerie\/"},{"@type":"ListItem","position":3,"name":"Muses"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/fr\/#website","url":"https:\/\/www.paolobigelli.com\/fr\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/fr\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product\/14704"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/comments?post=14704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/media\/14708"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/media?parent=14704"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product_cat?post=14704"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product_tag?post=14704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}