{"id":13851,"date":"2020-12-31T07:32:00","date_gmt":"2020-12-31T07:32:00","guid":{"rendered":"https:\/\/paolobigelli.com\/opera\/midi-marin\/"},"modified":"2020-12-31T07:32:00","modified_gmt":"2020-12-31T07:32:00","slug":"midi-marin","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/","title":{"rendered":"Midi marin"},"content":{"rendered":"<p>Tecnica mista su carta kraft<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tecnica mista su carta kraft &#8211; 2014 &#8211; 70x50cm<\/p>\n","protected":false},"featured_media":8496,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1961],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Midi marin - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Midi marin - Paolo Bigelli\" \/>\n<meta property=\"og:description\" content=\"Tecnica mista su carta kraft - 2014 - 70x50cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/\",\"name\":\"Midi marin - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg\",\"datePublished\":\"2020-12-31T07:32:00+00:00\",\"dateModified\":\"2020-12-31T07:32:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg\",\"width\":1032,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\/\/www.paolobigelli.com\/fr\/galerie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Midi marin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Midi marin - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/","og_locale":"fr_FR","og_type":"article","og_title":"Midi marin - Paolo Bigelli","og_description":"Tecnica mista su carta kraft - 2014 - 70x50cm","og_url":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","og_image":[{"width":1032,"height":700,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/","url":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/","name":"Midi marin - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg","datePublished":"2020-12-31T07:32:00+00:00","dateModified":"2020-12-31T07:32:00+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xa_Meriggio_marino-2.jpg","width":1032,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/fr\/oeuvre\/midi-marin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.paolobigelli.com\/fr\/galerie\/"},{"@type":"ListItem","position":3,"name":"Midi marin"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/fr\/#website","url":"https:\/\/www.paolobigelli.com\/fr\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/fr\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product\/13851"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/comments?post=13851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/media\/8496"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/media?parent=13851"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product_cat?post=13851"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/fr\/wp-json\/wp\/v2\/product_tag?post=13851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}