{"id":14864,"date":"2021-04-08T07:41:50","date_gmt":"2021-04-08T07:41:51","guid":{"rendered":"https:\/\/paolobigelli.com\/?post_type=product&#038;p=14864"},"modified":"2021-04-08T07:43:20","modified_gmt":"2021-04-08T07:43:20","slug":"the-corsair","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/","title":{"rendered":"The Corsair"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":14868,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1960],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Corsair - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Corsair - Paolo Bigelli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T07:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1535\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/\",\"url\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/\",\"name\":\"The Corsair - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg\",\"datePublished\":\"2021-04-08T07:41:51+00:00\",\"dateModified\":\"2021-04-08T07:43:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg\",\"width\":1535,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.paolobigelli.com\/en\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Corsair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/en\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Corsair - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/","og_locale":"en_US","og_type":"article","og_title":"The Corsair - Paolo Bigelli","og_url":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","article_modified_time":"2021-04-08T07:43:20+00:00","og_image":[{"width":1535,"height":2048,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/","url":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/","name":"The Corsair - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg","datePublished":"2021-04-08T07:41:51+00:00","dateModified":"2021-04-08T07:43:20+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2021\/04\/11401962@N02_49906208637_La-Corsara-The-Corsair.jpg","width":1535,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/en\/work\/the-corsair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.paolobigelli.com\/en\/gallery\/"},{"@type":"ListItem","position":3,"name":"The Corsair"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/en\/#website","url":"https:\/\/www.paolobigelli.com\/en\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/en\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product\/14864"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/comments?post=14864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/media\/14868"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/media?parent=14864"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product_cat?post=14864"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product_tag?post=14864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}