{"id":13658,"date":"2020-12-31T10:45:00","date_gmt":"2020-12-31T10:45:00","guid":{"rendered":"https:\/\/paolobigelli.com\/opera\/a-romantic-evening\/"},"modified":"2020-12-31T10:45:00","modified_gmt":"2020-12-31T10:45:00","slug":"a-romantic-evening","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/","title":{"rendered":"A romantic evening"},"content":{"rendered":"<p>Acrilico su carta Kraft<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acrilico su carta Kraft &#8211; 2017 &#8211; 100x75cm<\/p>\n","protected":false},"featured_media":8267,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1960],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A romantic evening - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A romantic evening - Paolo Bigelli\" \/>\n<meta property=\"og:description\" content=\"Acrilico su carta Kraft - 2017 - 100x75cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1374\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/\",\"url\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/\",\"name\":\"A romantic evening - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg\",\"datePublished\":\"2020-12-31T10:45:00+00:00\",\"dateModified\":\"2020-12-31T10:45:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg\",\"width\":1374,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.paolobigelli.com\/en\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A romantic evening\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/en\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A romantic evening - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/","og_locale":"en_US","og_type":"article","og_title":"A romantic evening - Paolo Bigelli","og_description":"Acrilico su carta Kraft - 2017 - 100x75cm","og_url":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","og_image":[{"width":1374,"height":1000,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/","url":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/","name":"A romantic evening - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg","datePublished":"2020-12-31T10:45:00+00:00","dateModified":"2020-12-31T10:45:00+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/vo_Una-serata-romantica-2.jpg","width":1374,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/en\/work\/a-romantic-evening\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.paolobigelli.com\/en\/gallery\/"},{"@type":"ListItem","position":3,"name":"A romantic evening"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/en\/#website","url":"https:\/\/www.paolobigelli.com\/en\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/en\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product\/13658"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/comments?post=13658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/media\/8267"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/media?parent=13658"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product_cat?post=13658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/en\/wp-json\/wp\/v2\/product_tag?post=13658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}