{"id":14020,"date":"2020-12-31T04:43:00","date_gmt":"2020-12-31T04:43:00","guid":{"rendered":"https:\/\/paolobigelli.com\/opera\/tajo-nymphen\/"},"modified":"2020-12-31T04:43:00","modified_gmt":"2020-12-31T04:43:00","slug":"tajo-nymphen","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/","title":{"rendered":"Tajo Nymphen"},"content":{"rendered":"<p>Acrilico su carta Kraft oro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acrilico su carta Kraft oro &#8211; 2013 &#8211; 200x150cm<\/p>\n","protected":false},"featured_media":8581,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1962],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tajo Nymphen - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tajo Nymphen - Paolo Bigelli\" \/>\n<meta property=\"og:description\" content=\"Acrilico su carta Kraft oro - 2013 - 200x150cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"867\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/\",\"url\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/\",\"name\":\"Tajo Nymphen - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg\",\"datePublished\":\"2020-12-31T04:43:00+00:00\",\"dateModified\":\"2020-12-31T04:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg\",\"width\":867,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.paolobigelli.com\/de\/galerie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tajo Nymphen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/de\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tajo Nymphen - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/","og_locale":"de_DE","og_type":"article","og_title":"Tajo Nymphen - Paolo Bigelli","og_description":"Acrilico su carta Kraft oro - 2013 - 200x150cm","og_url":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","og_image":[{"width":867,"height":650,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/","url":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/","name":"Tajo Nymphen - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg","datePublished":"2020-12-31T04:43:00+00:00","dateModified":"2020-12-31T04:43:00+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/xo_Tagidi-Tagus-Nymphs-Tajo-Nymphen-Nymphes-du-Tage-Tagides-2.jpg","width":867,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/de\/werke\/tajo-nymphen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.paolobigelli.com\/de\/galerie\/"},{"@type":"ListItem","position":3,"name":"Tajo Nymphen"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/de\/#website","url":"https:\/\/www.paolobigelli.com\/de\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/de\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product\/14020"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/comments?post=14020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/media\/8581"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/media?parent=14020"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product_cat?post=14020"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product_tag?post=14020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}