{"id":13997,"date":"2020-12-31T05:06:00","date_gmt":"2020-12-31T05:06:00","guid":{"rendered":"https:\/\/paolobigelli.com\/opera\/manticore\/"},"modified":"2020-12-31T05:06:00","modified_gmt":"2020-12-31T05:06:00","slug":"manticore","status":"publish","type":"product","link":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/","title":{"rendered":"Manticore"},"content":{"rendered":"<p>Tecnica mista su carta Kraft<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tecnica mista su carta Kraft &#8211; 2015 &#8211; 150x100cm<\/p>\n","protected":false},"featured_media":8443,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[1962],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manticore - Paolo Bigelli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manticore - Paolo Bigelli\" \/>\n<meta property=\"og:description\" content=\"Tecnica mista su carta Kraft - 2015 - 150x100cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/\" \/>\n<meta property=\"og:site_name\" content=\"Paolo Bigelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pbigelli\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/\",\"url\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/\",\"name\":\"Manticore - Paolo Bigelli\",\"isPartOf\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg\",\"datePublished\":\"2020-12-31T05:06:00+00:00\",\"dateModified\":\"2020-12-31T05:06:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#primaryimage\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg\",\"width\":1000,\"height\":646},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.paolobigelli.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.paolobigelli.com\/de\/galerie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manticore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#website\",\"url\":\"https:\/\/www.paolobigelli.com\/de\/\",\"name\":\"Paolo Bigelli\",\"description\":\"Pittore in Roma\",\"publisher\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.paolobigelli.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#organization\",\"name\":\"Paolo Bigelli\",\"url\":\"https:\/\/www.paolobigelli.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"contentUrl\":\"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png\",\"width\":200,\"height\":100,\"caption\":\"Paolo Bigelli\"},\"image\":{\"@id\":\"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pbigelli\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manticore - Paolo Bigelli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/","og_locale":"de_DE","og_type":"article","og_title":"Manticore - Paolo Bigelli","og_description":"Tecnica mista su carta Kraft - 2015 - 150x100cm","og_url":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/","og_site_name":"Paolo Bigelli","article_publisher":"https:\/\/www.facebook.com\/pbigelli\/","og_image":[{"width":1000,"height":646,"url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/","url":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/","name":"Manticore - Paolo Bigelli","isPartOf":{"@id":"https:\/\/www.paolobigelli.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#primaryimage"},"image":{"@id":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg","datePublished":"2020-12-31T05:06:00+00:00","dateModified":"2020-12-31T05:06:00+00:00","breadcrumb":{"@id":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#primaryimage","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/wr_Manticore-Tecnica-mista-su-carta-kraft-cm150x100-2015-1.jpg","width":1000,"height":646},{"@type":"BreadcrumbList","@id":"https:\/\/www.paolobigelli.com\/de\/werke\/manticore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paolobigelli.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.paolobigelli.com\/de\/galerie\/"},{"@type":"ListItem","position":3,"name":"Manticore"}]},{"@type":"WebSite","@id":"https:\/\/www.paolobigelli.com\/de\/#website","url":"https:\/\/www.paolobigelli.com\/de\/","name":"Paolo Bigelli","description":"Pittore in Roma","publisher":{"@id":"https:\/\/www.paolobigelli.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paolobigelli.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.paolobigelli.com\/de\/#organization","name":"Paolo Bigelli","url":"https:\/\/www.paolobigelli.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","contentUrl":"https:\/\/www.paolobigelli.com\/wp-content\/uploads\/2020\/12\/logo2.png","width":200,"height":100,"caption":"Paolo Bigelli"},"image":{"@id":"https:\/\/www.paolobigelli.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pbigelli\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product\/13997"}],"collection":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/comments?post=13997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/media\/8443"}],"wp:attachment":[{"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/media?parent=13997"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product_cat?post=13997"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.paolobigelli.com\/de\/wp-json\/wp\/v2\/product_tag?post=13997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}